{"id":7732,"date":"2025-03-19T11:22:01","date_gmt":"2025-03-19T09:22:01","guid":{"rendered":"https:\/\/turquoisedahabiya.com\/?post_type=tour&#038;p=7732"},"modified":"2026-01-18T20:41:09","modified_gmt":"2026-01-18T18:41:09","slug":"croisiere-sur-le-nil-en-dahabeya-de-4-jours-dassouan-a-esna","status":"publish","type":"tour","link":"https:\/\/turquoisedahabiya.com\/fr\/tour\/croisiere-sur-le-nil-en-dahabeya-de-4-jours-dassouan-a-esna\/","title":{"rendered":"Eaux sacr\u00e9es \u2013 Croisi\u00e8re de 4 jours en dahabiya sur le Nil d\u2019Assouan \u00e0 Esna"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Naviguez au c\u0153ur de l\u2019\u00c9gypte antique \u00e0 bord de la dahabiya Scared Waters, lors d\u2019une croisi\u00e8re sur le Nil de quatre jours entre Assouan et Esna. Laissez-vous porter par les eaux paisibles du fleuve \u00e0 bord d\u2019un \u00e9l\u00e9gant bateau intimiste, o\u00f9 le temps semble ralentir et o\u00f9 l\u2019histoire se m\u00eale aux souffles du d\u00e9sert. D\u00e9couvrez des tr\u00e9sors pr\u00e9serv\u00e9s comme les temples de Kom Ombo et d\u2019Edfou, fl\u00e2nez dans des villages hors du temps et admirez des couchers de soleil dor\u00e9s sur les rives du Nil. Entre service personnalis\u00e9, cuisine gastronomique et douceur d\u2019une navigation \u00e0 la voile, cette exp\u00e9rience exclusive allie luxe et authenticit\u00e9 pour un voyage intime au c\u0153ur de la terre des pharaons.   <\/p>\n","protected":false},"author":1,"featured_media":7743,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"tour_category":[203],"tour_tag":[],"tour-age":[],"tour-activity":[],"tour-destination":[206,205],"class_list":["post-7732","tour","type-tour","status-publish","has-post-thumbnail","hentry","tour_category-classic-tours","tour-destination-aswan","tour-destination-luxor"],"_links":{"self":[{"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour\/7732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour"}],"about":[{"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/types\/tour"}],"author":[{"embeddable":true,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":6,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour\/7732\/revisions"}],"predecessor-version":[{"id":8140,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour\/7732\/revisions\/8140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/media\/7743"}],"wp:attachment":[{"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/media?parent=7732"}],"wp:term":[{"taxonomy":"tour_category","embeddable":true,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour_category?post=7732"},{"taxonomy":"tour_tag","embeddable":true,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour_tag?post=7732"},{"taxonomy":"tour-age","embeddable":true,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour-age?post=7732"},{"taxonomy":"tour-activity","embeddable":true,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour-activity?post=7732"},{"taxonomy":"tour-destination","embeddable":true,"href":"https:\/\/turquoisedahabiya.com\/fr\/wp-json\/wp\/v2\/tour-destination?post=7732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}